{"id":28169,"date":"2022-03-10T17:06:39","date_gmt":"2022-03-10T17:06:39","guid":{"rendered":"https:\/\/www.talogy.com\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/"},"modified":"2026-07-10T16:47:41","modified_gmt":"2026-07-10T16:47:41","slug":"gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas","status":"publish","type":"post","link":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/","title":{"rendered":"Gamification pour un changement organisationnel positif &#8211; une \u00e9tude de cas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La gamification est une tendance \u00e9mergente qui a \u00e9t\u00e9 pr\u00e9sent\u00e9e comme un moteur d&rsquo;am\u00e9liorations mesurables de la productivit\u00e9 pour tous les types d&rsquo;industries. Si vous n&rsquo;avez pas entendu parler de gamification, cela se d\u00e9finit comme l&rsquo;application de m\u00e9canismes, d&rsquo;\u00e9l\u00e9ments et de fonctionnalit\u00e9s de jeu \u00e0 des situations non li\u00e9es au jeu. Dans le contexte organisationnel, il prend les aspects \u00ab ludiques \u00bb d&rsquo;un jeu et les applique aux process d&rsquo;entreprise. L&rsquo;objectif des programmes de gamification dans l&rsquo;environnement de travail est de stimuler l&rsquo;implication et l&rsquo;engagement des salari\u00e9s envers les objectifs organisationnels, ce qui \u00e0 son tour am\u00e9liorera la productivit\u00e9 et r\u00e9duira le turnover des salari\u00e9s.<\/p>\n\n<h2 class=\"wp-block-heading\">Comment \u00e7a marche&nbsp;?<\/h2>\n\n<p class=\"wp-block-paragraph\">Les syst\u00e8mes de gamification prennent des activit\u00e9s professionnelles typiques et les pr\u00e9sentent sous la forme d&rsquo;un jeu. Le jeu est rendu possible en d\u00e9finissant des objectifs engageants et tangibles \u00e0 poursuivre et \u00e0 d\u00e9passer. Diff\u00e9rentes r\u00e9alisations permettent aux salari\u00e9s d&rsquo;obtenir des r\u00e9compenses d\u00e9finies dans le syst\u00e8me de jeu. Par exemple, les vendeurs peuvent recevoir des badges de r\u00e9ussite pour avoir identifi\u00e9 un nombre requis de pistes de vente ou des m\u00e9dailles pour avoir d\u00e9pass\u00e9 les objectifs de vente. En outre, ces syst\u00e8mes permettent aux salari\u00e9s d&rsquo;\u00eatre reconnus par leurs coll\u00e8gues et peuvent donc encourager une concurrence saine. La cr\u00e9ation de concurrence entre les salari\u00e9s contribue non seulement \u00e0 augmenter la productivit\u00e9 et la rentabilit\u00e9, mais favorise \u00e9galement le renforcement des liens sociaux entre les salari\u00e9s. Des liens sociaux forts entre coll\u00e8gues sont associ\u00e9s \u00e0 de meilleures performances et \u00e0 une moindre probabilit\u00e9 de turnover.<\/p>\n\n<h2 class=\"wp-block-heading\">\u00c9tude de cas<\/h2>\n\n<p class=\"wp-block-paragraph\">Dans une \u00e9tude r\u00e9cente, nous nous sommes associ\u00e9s \u00e0 une grande organisation de grande distribution qui utilise les principes de la gamification dans sa plateforme de formation. Les salari\u00e9s rivalisent les uns avec les autres en suivant des modules de formation et d&rsquo;apprentissage. L&rsquo;interface de formation r\u00e9compense les salari\u00e9s avec des m\u00e9dailles et des badges obtenus en atteignant et en d\u00e9passant les objectifs associ\u00e9s \u00e0 la r\u00e9alisation de modules d&rsquo;apprentissage. La plateforme avait une grande visibilit\u00e9 au sein de l&rsquo;organisation, car tous les salari\u00e9s \u00e9taient encourag\u00e9s \u00e0 participer et pouvaient observer les niveaux de r\u00e9ussite de leurs coll\u00e8gues. <\/p>\n\n<p class=\"wp-block-paragraph\">Si l&rsquo;implication dans les syst\u00e8mes de gamification augmente la productivit\u00e9 et l&rsquo;engagement, nous nous attendons \u00e0 voir des niveaux plus \u00e9lev\u00e9s de performance professionnelle et de probabilit\u00e9 de r\u00e9tention chez les individus qui sont plus impliqu\u00e9s et qui r\u00e9ussissent dans le syst\u00e8me de gamification. Ainsi, nous avons compar\u00e9 la performance professionnelle et la probabilit\u00e9 de r\u00e9tention des salari\u00e9s qui ont atteint des niveaux \u00e9lev\u00e9s, mod\u00e9r\u00e9s et faibles de r\u00e9ussite sur le syst\u00e8me de gamification. <\/p>\n\n<p class=\"wp-block-paragraph\">Comme pr\u00e9vu, les salari\u00e9s qui ont obtenu un plus grand nombre de m\u00e9dailles et d&rsquo;insignes \u00e9taient deux fois plus susceptibles d&rsquo;\u00eatre class\u00e9s comme \u00ab Top Performers \u00bb par leurs superviseurs. Ces personnes \u00e9taient \u00e9galement plus de trois fois plus susceptibles d&rsquo;\u00eatre consid\u00e9r\u00e9es comme dispos\u00e9es \u00e0 rester au sein de l&rsquo;organisation. Il semble donc que, du moins dans cette organisation, le syst\u00e8me de gamification soit li\u00e9 \u00e0 certains r\u00e9sultats organisationnels positifs.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/talogy-gamification-for-positive-organizational-outcomes-graphs.jpg\" alt=\"talogy gamification for positive organizational outcomes graphs\"\/><\/figure>\n\n<h2 class=\"wp-block-heading\">Si vous voulez \u00ab&nbsp;gamifier&nbsp;\u00bb, tenez compte de ces quatre choses<\/h2>\n\n<p class=\"wp-block-paragraph\">Inspir\u00e9 par ces r\u00e9sultats ? Avant d&rsquo;introduire la gamification dans votre organisation, nous avons quelques suggestions bas\u00e9es sur nos recherches&nbsp;:<\/p>\n\n<ol class=\"wp-block-list\"><li><strong>Avoir des objectifs et des comportements bien d\u00e9finis que l&rsquo;organisation souhaite atteindre et encourager.<\/strong> Une bonne planification est importante. Ne n\u00e9gligez pas de tenir compte de la culture de l&rsquo;entreprise lorsque vous d\u00e9terminez ce qui sera un facteur de motivation efficace pour les salari\u00e9s.<\/li>\n\n<li><strong>Inclure des activit\u00e9s li\u00e9es \u00e0 des t\u00e2ches qui ont un sens pour vos salari\u00e9s.<\/strong> R\u00e9compenser les salari\u00e9s pour des t\u00e2ches banales et simples peut ne pas \u00eatre efficace. L&rsquo;organisation dans l&rsquo;\u00e9tude illustrative discut\u00e9e plus haut a r\u00e9ussi \u00e0 susciter l&rsquo;engagement parce que les t\u00e2ches \u00e9taient li\u00e9es \u00e0 une exp\u00e9rience d&rsquo;apprentissage enrichissante qui contribuait au d\u00e9veloppement global de la carri\u00e8re. En fin de compte, la gamification consiste \u00e0 impliquer les gens et \u00e0 les motiver \u00e0 atteindre des objectifs. Cela ne peut \u00eatre r\u00e9alis\u00e9 avec succ\u00e8s avec des \u00e9l\u00e9ments inint\u00e9ressants qui ne motivent pas intrins\u00e8quement les salari\u00e9s.<\/li>\n\n<li><strong>Assurez-vous que le programme a une grande visibilit\u00e9 et qu&rsquo;il est inclusif par de nombreux membres de l&rsquo;organisation.<\/strong>&nbsp;Ceci est essentiel \u00e0 l&rsquo;engagement et au succ\u00e8s du programme de gamification.<\/li>\n\n<li><strong>Attendez-vous \u00e0 des modifications du syst\u00e8me.<\/strong> Un suivi constant permettra de s&rsquo;assurer que les programmes de gamification restent conformes aux objectifs organisationnel et strat\u00e9giques.<\/li><\/ol>\n\n<p class=\"wp-block-paragraph\">Si cela est fait correctement, les organisations peuvent utiliser les principes de la gamification pour influencer les comportements de leurs salari\u00e9s , ce qui peut conduire \u00e0 de meilleurs r\u00e9sultats d&rsquo;entreprise.<\/p>\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"640\" height=\"828\" src=\"https:\/\/talogy.com\/wp-content\/uploads\/2021\/12\/cta-whitepaper-cover-artificial-intelligence-in-talent-management.webp\" alt=\"artificial intelligence in talent management cta whitepaper cover\" class=\"wp-image-4380 size-full\" srcset=\"https:\/\/talogy.com\/wp-content\/uploads\/2021\/12\/cta-whitepaper-cover-artificial-intelligence-in-talent-management.webp 640w, https:\/\/talogy.com\/wp-content\/uploads\/2021\/12\/cta-whitepaper-cover-artificial-intelligence-in-talent-management-232x300.webp 232w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><div class=\"wp-block-media-text__content\"><h2 class=\"wp-block-heading\">L&rsquo;intelligence artificielle dans Talent Management<\/h2>\n\n<h3 class=\"wp-block-heading\">Le potentiel de l&rsquo;intelligence artificielle (IA) pour am\u00e9liorer consid\u00e9rablement la fa\u00e7on dont nous recrutons et d\u00e9veloppons les talents est incroyablement excitant.<\/h3>\n\n<p class=\"wp-block-paragraph\">Mais soyons clairs, les r\u00e9sultats \u00e0 ce jour n&rsquo;ont pas toujours \u00e9t\u00e9 positifs. <\/p>\n\n<p class=\"wp-block-paragraph\">Dans ce livre blanc, nous fournissons un aper\u00e7u \u00e9quilibr\u00e9 et transparent des avantages et des inconv\u00e9nients de l&rsquo;utilisation de l&rsquo;IA dans Talent Management &#8211; en soulignant o\u00f9 notre industrie peut b\u00e9n\u00e9ficier de son puissant potentiel analytique et en signalant les domaines o\u00f9 les techniques d&rsquo;IA doivent \u00eatre approch\u00e9es avec prudence.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/info.talogy.com\/en-gb\/artificial-intelligence-talent-management\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9l\u00e9charger maintenant<\/a><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La gamification est une tendance \u00e9mergente qui a \u00e9t\u00e9 pr\u00e9sent\u00e9e comme un moteur d&rsquo;am\u00e9liorations mesurables de la productivit\u00e9 pour tous les types d&rsquo;industries. Si vous n&rsquo;avez pas entendu parler de gamification, cela se d\u00e9finit comme l&rsquo;application de m\u00e9canismes, d&rsquo;\u00e9l\u00e9ments et de fonctionnalit\u00e9s de jeu \u00e0 des situations non li\u00e9es au jeu. Dans le contexte organisationnel, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":104476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"custom_post_author_id":"106992","footnotes":""},"categories":[202],"tags":[],"tax_topic":[],"tax_industry":[552,543,546,551,544,545,548,547,549,550],"class_list":["post-28169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr","tax_industry-administrations","tax_industry-automobile","tax_industry-banque-assurance","tax_industry-commerce","tax_industry-energie","tax_industry-gouvernement-federal","tax_industry-industrie-fr","tax_industry-sante","tax_industry-services-entreprises","tax_industry-services-publics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gamification pour un changement organisationnel positif - une \u00e9tude de cas | Talogy<\/title>\n<meta name=\"description\" content=\"La gamification peut contribuer \u00e0 cr\u00e9er des r\u00e9sultats organisationnels positifs, comme le montre notre r\u00e9cente \u00e9tude de cas. Avant de gamifier, tenez compte de ces 4 points.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamification pour un changement organisationnel positif - une \u00e9tude de cas | Talogy\" \/>\n<meta property=\"og:description\" content=\"La gamification peut contribuer \u00e0 cr\u00e9er des r\u00e9sultats organisationnels positifs, comme le montre notre r\u00e9cente \u00e9tude de cas. Avant de gamifier, tenez compte de ces 4 points.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/\" \/>\n<meta property=\"og:site_name\" content=\"Talogy\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T17:06:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T16:47:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/talogy.com\/wp-content\/uploads\/2025\/04\/hero-v4-teal-background-woman-gold-glasses.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jason Griffith\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamification pour un changement organisationnel positif - une \u00e9tude de cas | Talogy","description":"La gamification peut contribuer \u00e0 cr\u00e9er des r\u00e9sultats organisationnels positifs, comme le montre notre r\u00e9cente \u00e9tude de cas. Avant de gamifier, tenez compte de ces 4 points.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/","og_locale":"fr_FR","og_type":"article","og_title":"Gamification pour un changement organisationnel positif - une \u00e9tude de cas | Talogy","og_description":"La gamification peut contribuer \u00e0 cr\u00e9er des r\u00e9sultats organisationnels positifs, comme le montre notre r\u00e9cente \u00e9tude de cas. Avant de gamifier, tenez compte de ces 4 points.","og_url":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/","og_site_name":"Talogy","article_published_time":"2022-03-10T17:06:39+00:00","article_modified_time":"2026-07-10T16:47:41+00:00","og_image":[{"width":770,"height":578,"url":"https:\/\/talogy.com\/wp-content\/uploads\/2025\/04\/hero-v4-teal-background-woman-gold-glasses.webp","type":"image\/jpeg"}],"author":"Jason Griffith","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#article","isPartOf":{"@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/"},"author":{"name":"Jason Griffith","@id":"https:\/\/talogy.com\/fr\/#\/schema\/person\/0fa2d90e6214d4338a03f025e137cda3"},"headline":"Gamification pour un changement organisationnel positif &#8211; une \u00e9tude de cas","datePublished":"2022-03-10T17:06:39+00:00","dateModified":"2026-07-10T16:47:41+00:00","mainEntityOfPage":{"@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/"},"wordCount":984,"commentCount":0,"publisher":{"@id":"https:\/\/talogy.com\/fr\/#organization"},"image":{"@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#primaryimage"},"thumbnailUrl":"https:\/\/talogy.com\/wp-content\/uploads\/2025\/04\/hero-v4-teal-background-woman-gold-glasses.webp","articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/","url":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/","name":"Gamification pour un changement organisationnel positif - une \u00e9tude de cas | Talogy","isPartOf":{"@id":"https:\/\/talogy.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#primaryimage"},"image":{"@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#primaryimage"},"thumbnailUrl":"https:\/\/talogy.com\/wp-content\/uploads\/2025\/04\/hero-v4-teal-background-woman-gold-glasses.webp","datePublished":"2022-03-10T17:06:39+00:00","dateModified":"2026-07-10T16:47:41+00:00","description":"La gamification peut contribuer \u00e0 cr\u00e9er des r\u00e9sultats organisationnels positifs, comme le montre notre r\u00e9cente \u00e9tude de cas. Avant de gamifier, tenez compte de ces 4 points.","breadcrumb":{"@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#primaryimage","url":"https:\/\/talogy.com\/wp-content\/uploads\/2025\/04\/hero-v4-teal-background-woman-gold-glasses.webp","contentUrl":"https:\/\/talogy.com\/wp-content\/uploads\/2025\/04\/hero-v4-teal-background-woman-gold-glasses.webp","width":770,"height":578,"caption":"woman wearing gold glasses"},{"@type":"BreadcrumbList","@id":"https:\/\/talogy.com\/fr\/blog\/gamification-pour-un-changement-organisationnel-positif-une-etude-de-cas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/talogy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/talogy.com\/fr\/blog\/"},{"@type":"ListItem","position":3,"name":"Gamification pour un changement organisationnel positif &#8211; une \u00e9tude de cas"}]},{"@type":"WebSite","@id":"https:\/\/talogy.com\/fr\/#website","url":"https:\/\/talogy.com\/fr\/","name":"Talogy","description":"Talogy Website","publisher":{"@id":"https:\/\/talogy.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/talogy.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/talogy.com\/fr\/#organization","name":"Talogy","url":"https:\/\/talogy.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/talogy.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/talogy.com\/wp-content\/uploads\/2022\/02\/logo-welcome.png","contentUrl":"https:\/\/talogy.com\/wp-content\/uploads\/2022\/02\/logo-welcome.png","width":336,"height":103,"caption":"Talogy"},"image":{"@id":"https:\/\/talogy.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/talogy\/"]},{"@type":"Person","@id":"https:\/\/talogy.com\/fr\/#\/schema\/person\/0fa2d90e6214d4338a03f025e137cda3","name":"Jason Griffith"}]}},"_links":{"self":[{"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/posts\/28169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/comments?post=28169"}],"version-history":[{"count":5,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/posts\/28169\/revisions"}],"predecessor-version":[{"id":144491,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/posts\/28169\/revisions\/144491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/media\/104476"}],"wp:attachment":[{"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/media?parent=28169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/categories?post=28169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/tags?post=28169"},{"taxonomy":"tax_topic","embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/tax_topic?post=28169"},{"taxonomy":"tax_industry","embeddable":true,"href":"https:\/\/talogy.com\/fr\/wp-json\/wp\/v2\/tax_industry?post=28169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}