{"id":120452,"date":"2025-09-12T18:25:27","date_gmt":"2025-09-12T18:25:27","guid":{"rendered":"https:\/\/content-stg-talogy.pantheonsite.io\/?post_type=authors&#038;p=120452"},"modified":"2025-11-15T10:38:31","modified_gmt":"2025-11-15T10:38:31","slug":"rachel-schremp","status":"publish","type":"authors","link":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/","title":{"rendered":"Rachel Schremp"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"wds_authors_title":"Senior Consulting Associate","wds_authors_biography":"Rachel ist Senior Consulting Associate bei Talogy. Sie hat sowohl ihren M.A. in TESOL als auch ihren M.A. in Arbeits- und Organisationspsychologie an der Southeast Missouri State University erworben. Rachel bringt vielf\u00e4ltige Interessen und Erfahrungen mit, darunter Training, F\u00fchrungskr\u00e4fte- und Organisationsentwicklung sowie Unternehmenskultur. Bei Talogy betreut sie Talententwicklungsprogramme f\u00fcr ihre Kund:innen und unterst\u00fctzt sie bei der Auswahl von Kandidat:innen mit passender Eignung. Die Zusammenarbeit mit anderen und die Umsetzung von Initiativen zur F\u00f6rderung einer positiven Unternehmenskultur geben ihr die M\u00f6glichkeit, ihre Kreativit\u00e4t und sozialen F\u00e4higkeiten einzusetzen \u2013 zwei Dinge, die sie so oft wie m\u00f6glich zu f\u00f6rdern versucht.","wds_authors_id":"","footnotes":""},"class_list":["post-120452","authors","type-authors","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rachel Schremp | Talogy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rachel Schremp | Talogy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/\" \/>\n<meta property=\"og:site_name\" content=\"Talogy\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-15T10:38:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rachel Schremp | Talogy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/","og_locale":"de_DE","og_type":"article","og_title":"Rachel Schremp | Talogy","og_url":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/","og_site_name":"Talogy","article_modified_time":"2025-11-15T10:38:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/","url":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/","name":"Rachel Schremp | Talogy","isPartOf":{"@id":"https:\/\/talogy.com\/de\/#website"},"datePublished":"2025-09-12T18:25:27+00:00","dateModified":"2025-11-15T10:38:31+00:00","breadcrumb":{"@id":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/talogy.com\/de\/autoren\/rachel-schremp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/talogy.com\/de\/"},{"@type":"ListItem","position":2,"name":"Rachel Schremp"}]},{"@type":"WebSite","@id":"https:\/\/talogy.com\/de\/#website","url":"https:\/\/talogy.com\/de\/","name":"Talogy","description":"Talogy Website","publisher":{"@id":"https:\/\/talogy.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/talogy.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/talogy.com\/de\/#organization","name":"Talogy","url":"https:\/\/talogy.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/talogy.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/talogy.com\/wp-content\/uploads\/2022\/02\/logo-welcome.png","contentUrl":"https:\/\/talogy.com\/wp-content\/uploads\/2022\/02\/logo-welcome.png","width":336,"height":103,"caption":"Talogy"},"image":{"@id":"https:\/\/talogy.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/talogy\/"]}]}},"_links":{"self":[{"href":"https:\/\/talogy.com\/de\/wp-json\/wp\/v2\/authors\/120452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talogy.com\/de\/wp-json\/wp\/v2\/authors"}],"about":[{"href":"https:\/\/talogy.com\/de\/wp-json\/wp\/v2\/types\/authors"}],"version-history":[{"count":1,"href":"https:\/\/talogy.com\/de\/wp-json\/wp\/v2\/authors\/120452\/revisions"}],"predecessor-version":[{"id":120460,"href":"https:\/\/talogy.com\/de\/wp-json\/wp\/v2\/authors\/120452\/revisions\/120460"}],"wp:attachment":[{"href":"https:\/\/talogy.com\/de\/wp-json\/wp\/v2\/media?parent=120452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}